{"id":1280,"date":"2016-08-25T17:41:34","date_gmt":"2016-08-25T17:41:34","guid":{"rendered":"https:\/\/emanpackaging.com\/fr\/all4pack_paris\/"},"modified":"2024-07-24T08:49:34","modified_gmt":"2024-07-24T08:49:34","slug":"all4pack_paris","status":"publish","type":"post","link":"https:\/\/emanpackaging.com\/fr\/all4pack_paris\/","title":{"rendered":"Participamos en la feria All4Pack &#8211; Emballage 2016 de Par\u00eds"},"content":{"rendered":"<h4 data-fontsize=\"14\" data-lineheight=\"20\"><img decoding=\"async\" class=\"alignnone size-full wp-image-1259\" src=\"https:\/\/emanpackaging.com\/wp-content\/uploads\/2016\/09\/eman-nde-emballage.jpg\" alt=\"eman-nde-emballage\" width=\"1856\" height=\"1306\" srcset=\"https:\/\/emanpackaging.com\/wp-content\/uploads\/2016\/09\/eman-nde-emballage-300x211.jpg 300w, https:\/\/emanpackaging.com\/wp-content\/uploads\/2016\/09\/eman-nde-emballage-768x540.jpg 768w, https:\/\/emanpackaging.com\/wp-content\/uploads\/2016\/09\/eman-nde-emballage-1024x721.jpg 1024w, https:\/\/emanpackaging.com\/wp-content\/uploads\/2016\/09\/eman-nde-emballage.jpg 1856w\" sizes=\"(max-width: 1856px) 100vw, 1856px\" \/><\/h4>\n<h4 data-fontsize=\"14\" data-lineheight=\"20\">Estamos muy contentos de anunciaros nuestra presencia en la Feria Internacional Emballage All4Pack 2016 de Par\u00eds del 14 al 17 de Noviembre.<\/h4>\n<p>La Feria <a href=\"https:\/\/www.all4pack.com\/\" target=\"_blank\" rel=\"noopener\">All4Pack Emballage<\/a> es el punto de encuentro m\u00e1s importante del sector del embalaje en Europa. Participar\u00e1n al rededor de 1.500 expositores, de m\u00e1s de 100 pa\u00edses, y se esperan m\u00e1s de 100.000 visitantes. Es el mejor escaparate para descubrir las \u00faltimas soluciones de envasado, con la tecnolog\u00eda m\u00e1s avanzada.<span id=\"more-1715\"><\/span><\/p>\n<p>Desde Eman Packaging expondremos en nuestro stand las \u00faltimas tendencias y soluciones t\u00e9cnicas tanto de Packaging. Adem\u00e1s compartiremos el stand con la empresa <a href=\"http:\/\/www.etiquetasnde.com\/\" target=\"_blank\" rel=\"noopener\">Etiquetas de Navarra<\/a>, perteneciente tambi\u00e9n al <a href=\"http:\/\/docu-world.com\/\" target=\"_blank\" rel=\"noopener\">Grupo Docu-World<\/a>.<\/p>\n<p style=\"text-align: center;\"><strong>Nuestro stand estar\u00e1 ubicado en el HALL 7 D 122<\/strong><\/p>\n<p>Si quer\u00e9is aprovechar la ocasi\u00f3n para conocernos, estaremos encantados de saludaros. Tambi\u00e9n pod\u00e9is concertar una reuni\u00f3n personal escribiendo a <a href=\"mailto:graficas@eman.es\">Eman Packaging<\/a> o a <a href=\"mailto:info@e-nde.com\" target=\"_blank\" rel=\"noopener\">Etiquetas de Navarra<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estamos muy contentos de anunciaros nuestra presencia en la Feria Internacional Emballage All4Pack 2016 de Par\u00eds del 14 al 17 de Noviembre. La Feria All4Pack Emballage es el punto de encuentro m\u00e1s importante del sector del embalaje en Europa. Participar\u00e1n al rededor de 1.500 expositores, de m\u00e1s de 100 pa\u00edses, y se esperan m\u00e1s de  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":1259,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[270],"tags":[271,272,273,274,275,276],"class_list":["post-1280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eman-fr","tag-2016-fr","tag-eman-fr","tag-emballage-fr","tag-feria-fr","tag-grupo-docu-world-fr","tag-packaging-2-fr"],"_links":{"self":[{"href":"https:\/\/emanpackaging.com\/fr\/wp-json\/wp\/v2\/posts\/1280"}],"collection":[{"href":"https:\/\/emanpackaging.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emanpackaging.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emanpackaging.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emanpackaging.com\/fr\/wp-json\/wp\/v2\/comments?post=1280"}],"version-history":[{"count":2,"href":"https:\/\/emanpackaging.com\/fr\/wp-json\/wp\/v2\/posts\/1280\/revisions"}],"predecessor-version":[{"id":24729,"href":"https:\/\/emanpackaging.com\/fr\/wp-json\/wp\/v2\/posts\/1280\/revisions\/24729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emanpackaging.com\/fr\/wp-json\/wp\/v2\/media\/1259"}],"wp:attachment":[{"href":"https:\/\/emanpackaging.com\/fr\/wp-json\/wp\/v2\/media?parent=1280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emanpackaging.com\/fr\/wp-json\/wp\/v2\/categories?post=1280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emanpackaging.com\/fr\/wp-json\/wp\/v2\/tags?post=1280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}